{"id":51275,"date":"2022-09-20T09:18:36","date_gmt":"2022-09-20T02:18:36","guid":{"rendered":"https:\/\/www.globallandscapesforum.org\/?post_type=corporate_news&#038;p=51275"},"modified":"2022-09-22T13:44:17","modified_gmt":"2022-09-22T06:44:17","slug":"en-plein-pendant-les-crises-climatiques-et-alimentaires-mondiales-lafrique-se-construit-un-avenir-alimentaire-plus-radieux","status":"publish","type":"corporate_news","link":"https:\/\/www.globallandscapesforum.org\/fr\/glf-news\/en-plein-pendant-les-crises-climatiques-et-alimentaires-mondiales-lafrique-se-construit-un-avenir-alimentaire-plus-radieux\/","title":{"rendered":"En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"51275\" class=\"elementor elementor-51275 elementor-51213\" data-elementor-post-type=\"corporate_news\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-def8f36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"def8f36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6354339\" data-id=\"6354339\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-914396b elementor-widget elementor-widget-text-editor\" data-id=\"914396b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span lang=\"FR\">Photo par Axel Fassio \/ CIFOR<\/span><span lang=\"FR\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a4530 elementor-widget elementor-widget-text-editor\" data-id=\"80a4530\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"x_MsoNormal\" style=\"text-align: left;\" align=\"center\">POUR DIFFUSION IMM\u00c9DIATE | <i>In the <a title=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/newsroom\/\" contenteditable=\"false\" href=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/newsroom\/\">newsroom<\/a><\/i><i>: <a href=\"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/\">English<\/a>, <a href=\"https:\/\/www.globallandscapesforum.org\/de\/glf-news\/trotz-globaler-klima-und-hungerkrise-afrika-arbeitet-an-zukuenftiger-lebensmittelsicherheit-fuer-den-kontinent\/\">Deutsche<\/a>\u00a0<\/i><\/p><p><span class=\"x_normaltextrun\"><b><span lang=\"FR\">BONN, Allemagne<\/span><\/b><\/span><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\"> (15<\/span>\u00a0septembre\u202f2022)\u202f\u2013\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contribue qu\u2019<\/span>\u00e0 hauteur de 4\u00a0% aux \u00e9missions mondiales de gaz \u00e0 effet de serre. La guerre en Ukraine entra\u00eene une hausse spectaculaire des prix des denr\u00e9es alimentaires et des carburants, ce qui fait qu\u2019il est plus difficile que jamais pour les pays africains de nourrir leurs citoyennes et citoyens gr\u00e2ce aux importations alimentaires. Toutefois, la crise pourrait \u00e9galement offrir \u00e0 l\u2019Afrique l\u2019opportunit\u00e9 de transformer radicalement ses syst\u00e8mes alimentaires, ont d\u00e9clar\u00e9 des experts lors de la <\/span><a style=\"background-color: #ffffff;\" title=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/\" contenteditable=\"false\" href=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">Conf\u00e9rence num\u00e9rique GLF\u202fAfrica\u00a02022<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">.<\/span><\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Le continent <\/span>africain dispose d\u2019une multitude de solutions pour reprendre sa souverainet\u00e9 alimentaire, mais ces solutions doivent \u00eatre d\u00e9velopp\u00e9es. Plus de 200\u00a0intervenant(e)s ont lanc\u00e9 un appel <\/span>\u00e0 la mobilisation\u00a0pour des investissements dans le climat et la biodiversit\u00e9, l\u2019acc\u00e8s \u00e9quitable \u00e0 la terre, et des cha\u00eenes de valeur plus courtes et plus \u00e9cologiques. Non seulement cette transformation peut renforcer la r\u00e9silience des communaut\u00e9s et des \u00e9cosyst\u00e8mes, mais elle peut \u00e9galement att\u00e9nuer les effets du changement climatique.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">\u00ab\u202f<\/span>Jamais auparavant nous n\u2019avons \u00e9t\u00e9 confront\u00e9s simultan\u00e9ment \u00e0 autant de crises mondiales qu\u2019aujourd\u2019hui. Aujourd\u2019hui, nous devons non seulement prendre des mesures contre l\u2019une des pires crises alimentaires mondiales jamais connues, mais nous devons \u00e9galement rendre nos syst\u00e8mes alimentaires davantage r\u00e9silients aux crises futures. Consid\u00e9rons cela comme une opportunit\u00e9\u202f\u00bb, a d\u00e9clar\u00e9 <\/span><\/span><a title=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/speaker\/jochen-flasbarth\/\" contenteditable=\"false\" href=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/speaker\/jochen-flasbarth\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">Jochen\u202fFlasbarth<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">, <\/span>Secr\u00e9taire d\u2019<\/span>\u00c9tat au minist\u00e8re f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du D\u00e9veloppement (BMZ). L\u2019Allemagne pr\u00e9side actuellement le G7.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">\u00ab\u202f<\/span>La jeunesse africaine s\u2019est r\u00e9veill\u00e9e, et nous sommes d\u00e9termin\u00e9s \u00e0 faire tout ce qui est en notre pouvoir pour construire une Afrique prosp\u00e8re. Pour cela, nous avons besoin que les dirigeants africains encouragent activement les investissements dans le secteur agricole. Apr\u00e8s tout, l\u2019agriculture est le m\u00e9tier le plus formidable au monde. L\u2019agro-industrie africaine vaudra 1\u202f000\u00a0milliards de dollars d\u2019ici \u00e0 2030, et tout le monde a besoin de manger\u202f\u00bb, a soulign\u00e9 <\/span><a title=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/64ebf7a6-c003-ed11-b47a-a04a5e7cf9da\" contenteditable=\"false\" href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/64ebf7a6-c003-ed11-b47a-a04a5e7cf9da\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Ineza\u202fGrace<\/span><\/span><\/a><\/span><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">, coordinatrice de <\/span>Loss\u202fand\u202fDamage\u202fYouth\u202fCoalition (LDYC).<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Organis\u00e9 par le <\/span><\/span><\/span><a title=\"https:\/\/www.globallandscapesforum.org\/\" contenteditable=\"false\" href=\"https:\/\/www.globallandscapesforum.org\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">Global Landscapes Forum<\/span><\/span><\/span><\/a><span class=\"x_normaltextrun\"><span lang=\"FR\"><span data-contrast=\"auto\"> en partenariat avec le <\/span>minist\u00e8re f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du D\u00e9veloppement (BMZ) et divers partenaires, l&#8217;\u00e9v\u00e9nement enti\u00e8rement en ligne du 15\u00a0septembre\u202f2022 a rassembl\u00e9 plus de 8\u202f300\u00a0participant(e)s issus de 122\u00a0pays, dont des entrepreneurs, des scientifiques, des jeunes militants, des praticiens de la restauration et les plus hauts repr\u00e9sentants de gouvernements. Le Forum a permis de toucher plus de 26\u00a0millions de personnes gr\u00e2ce aux m\u00e9dias sociaux.<\/span><\/span><span class=\"x_eop\"><span lang=\"FR\"><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Avec 31<\/span>\u00a0sessions, la publication de cinq\u202f<\/span><\/span><a title=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/white-papers\/\" contenteditable=\"false\" href=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/white-papers\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">livres\u202fblancs<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">, des <\/span>tribunes, une visite virtuelle, un salon de l&#8217;emploi et des expositions et pr\u00e9sentations cr\u00e9atives, la conf\u00e9rence a fourni des informations essentielles sur la fa\u00e7on de construire un avenir alimentaire r\u00e9silient en Afrique avant la <\/span><\/span><a title=\"https:\/\/unfccc.int\/fr\/node\/568190\" contenteditable=\"false\" href=\"https:\/\/unfccc.int\/fr\/node\/568190\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">Conf\u00e9rence des Nations\u202fUnies sur le climat (COP27)<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\">\u00a0\u00e0 Sharm\u202fEl-Sheikh, en \u00c9gypte.<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><b><span lang=\"FR\">Parmi les principales recommandations formul\u00e9es par les experts de toute l<\/span>\u2019Afrique, citons celles qui suivent\u00a0:<\/b><\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><b><span lang=\"FR\">\u00a0<\/span><\/b><\/span><\/span><b><span lang=\"FR\">\u00a0<\/span><\/b><\/p><ul><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">L<\/span>\u2019Afrique est dot\u00e9e d\u2019<\/span>\u00e9cosyst\u00e8mes riches et diversifi\u00e9s qui fournissent des services essentiels pour garantir les besoins du continent en mati\u00e8re d\u2019alimentation, d\u2019eau, de sant\u00e9, d\u2019\u00e9nergie et de s\u00e9curit\u00e9 des moyens de subsistance. Dans les zones rurales du continent, plus de 62\u00a0% de la population d\u00e9pend directement de ces services. \u00c0 ce titre, la biodiversit\u00e9 et son impact doivent \u00eatre int\u00e9gr\u00e9s dans les prises d\u00e9cisionnelles \u00e9conomiques et financi\u00e8res.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Pour garantir une gestion durable des terres, les populations locales doivent b\u00e9n\u00e9ficier d<\/span>\u2019un acc\u00e8s \u00e9quitable aux terres et aux ressources naturelles, ind\u00e9pendamment de leur sexe et de leur \u00e2ge.<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Les jeunes ont un r\u00f4le <\/span>essentiel<\/span> \u00e0 jouer dans la construction de l\u2019avenir alimentaire du continent, mais la plupart des programmes de d\u00e9veloppement agricole en Afrique manquent de politiques qui les ciblent explicitement.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Les petits exploitants agricoles contribuent \u00e0 au moins 70<\/span>\u00a0% de l\u2019approvisionnement alimentaire de l\u2019Afrique, mais ils sont confront\u00e9s \u00e0 de multiples obstacles, notamment un acc\u00e8s insuffisant aux march\u00e9s, l\u2019inaction des politiques et des d\u00e9ficits technologiques qui limitent la productivit\u00e9 et la rentabilit\u00e9. Les pistes en mati\u00e8re de financement durable et de d\u00e9veloppement peuvent faire la diff\u00e9rence en am\u00e9liorant l\u2019utilisation des terres pour les syst\u00e8mes alimentaires africains et en cr\u00e9ant des emplois et des cha\u00eenes de valeur \u00ab\u202fverts\u202f\u00bb pour des produits de base comme le cacao, le soja, l\u2019huile de palme, les fruits et les l\u00e9gumes, avec des retomb\u00e9es positives sur le changement climatique, la biodiversit\u00e9, l\u2019utilisation de l\u2019eau, la pauvret\u00e9 rurale et les in\u00e9galit\u00e9s femmes-hommes.\u00a0<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/li><li><div><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">L<\/span>\u2019Afrique ne <\/span><\/span><a title=\"https:\/\/www.globallandscapesforum.org\/publication\/finance-sustainable-agriculture-africa\/\" contenteditable=\"false\" href=\"https:\/\/www.globallandscapesforum.org\/publication\/finance-sustainable-agriculture-africa\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">re\u00e7oit actuellement que 3\u00a0% dufinancement climatique mondial<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\"> alors qu<\/span>\u2019elle est l\u2019un des continents les plus touch\u00e9s par le changement climatique. Le d\u00e9ficit de financement des petites et moyennes entreprises agricoles en Afrique\u202fsubsaharienne est estim\u00e9 \u00e0 plus de 100\u00a0milliards de dollars par an, et l\u2019Afrique aura besoin de plus de 3\u202f000\u00a0milliards de dollars de financement climatique d\u2019ici 2030 pour atteindre les objectifs de l\u2019Accord\u202fde\u202fParis.\u00a0<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/div><\/li><\/ul><div><p class=\"x_paragraph\"><span class=\"x_normaltextrun\"><span lang=\"FR\">La conf\u00e9rence comprenait <\/span><\/span><a title=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/session\/7586ec28-c80c-ed11-bd6e-a04a5e7d2ab9\" contenteditable=\"false\" href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/session\/7586ec28-c80c-ed11-bd6e-a04a5e7d2ab9\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">une\u202fs\u00e9ance pl\u00e9ni\u00e8re<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\"> organis\u00e9e par le <\/span><\/span><\/span><a title=\"https:\/\/www.folur.org\/\" contenteditable=\"false\" href=\"https:\/\/www.folur.org\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">Programme d\u2019impact sur les syst\u00e8mes alimentaires, l\u2019utilisation des terres et la restauration<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"> <span lang=\"FR\">(<\/span><i><\/i><i>Food Systems, Land Use and Restoration<\/i><\/span>ou FOLUR), financ\u00e9 par le <\/span><a title=\"https:\/\/www.thegef.org\/\" contenteditable=\"false\" href=\"https:\/\/www.thegef.org\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">Fonds pour l\u2019environnement mondial (FEM)<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">, qui vise \u00e0 <\/span>transformer l\u2019empreinte environnementale de l\u2019agriculture via 27\u00a0projets nationaux ciblant les paysages de production de huit grands produits de base, dont le cacao, le caf\u00e9, le ma\u00efs, le b\u00e9tail, l\u2019huile de palme, le riz, le soja et le bl\u00e9. La s\u00e9ance pl\u00e9ni\u00e8re a permis de pr\u00e9senter des projets nationaux\u202fFOLUR r\u00e9cemment lanc\u00e9s en C\u00f4te\u202fd\u2019Ivoire et au Ghana, les deux plus grands pays exportateurs de cacao au monde, et a pr\u00e9sent\u00e9 des enseignements et des perspectives sur les moyens de r\u00e9aliser des cha\u00eenes de valeur de produits de base \u00e9cologiques et sans d\u00e9forestation.<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><\/div><p class=\"x_MsoNormal\"><span lang=\"FR\">#ThinkLandscape\u00a0#GLFAfrica<\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_MsoNormal\" align=\"center\"><i><span lang=\"FR\">### \u00a0<\/span><\/i><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_MsoNormal\"><b>NOTES AUX \u00c9DITEURS\u00a0<\/b><\/p><div><ul><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Retrouvez ci-dessous une s\u00e9lection de citations issues de <\/span>plusieurs sessions du GLF\u202fAfrica\u00a02022.<\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span>\u00a0<\/span><\/span><\/li><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Pour plus d<\/span>\u2019informations, pour organiser des entretiens avec les intervenants ou pour acc\u00e9der aux enregistrements des <a title=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/sessions\" contenteditable=\"false\" href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/sessions\">s\u00e9ances de la conf\u00e9rence<\/a>, veuillez contacter Kelly Quintero \u00e0 l<\/span>\u2019adresse suivante\u00a0: <\/span><a title=\"mailto:k.quintero@cgiar.org\" contenteditable=\"false\" href=\"mailto:k.quintero@cgiar.org\"><span lang=\"FR\">k.quintero@cgiar.org<\/span><\/a><span lang=\"FR\">.<\/span><span lang=\"FR\">\u00a0<\/span><\/li><li><span class=\"x_normaltextrun\"><span lang=\"FR\">Retrouvez ici une <\/span><\/span><a id=\"OWAa511148b-f2b6-fdf6-7c4b-fa4a11d6826e\" class=\"x_OWAAutoLink\" title=\"https:\/\/cgiar-my.sharepoint.com\/:f:\/g\/personal\/k_quintero_cgiar_org\/EmPODJJiYIpPtpXvGG-d6NYBXxk55iIrUl5Sskyf0vo8yA?e=Gl7Bna\" contenteditable=\"false\" href=\"https:\/\/cgiar-my.sharepoint.com\/:f:\/g\/personal\/k_quintero_cgiar_org\/EmPODJJiYIpPtpXvGG-d6NYBXxk55iIrUl5Sskyf0vo8yA?e=Gl7Bna\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">s\u00e9lection de photos<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"> et bien d\u2019autres visuels dans cette <\/span><\/span><a title=\"https:\/\/trello.com\/c\/hjWu572a\/5-official-hashtag-glfafrica\" contenteditable=\"false\" href=\"https:\/\/trello.com\/c\/hjWu572a\/5-official-hashtag-glfafrica\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">bo\u00eete \u00e0 outils pour les r\u00e9seaux sociaux<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"> \u00a0<\/span><\/span><\/li><li><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Retrouvez des ressources suppl\u00e9mentaires et les versions anglaise et allemande de cet avis aux m\u00e9dias dans la <\/span><\/span><\/span><a title=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/newsroom\/\" contenteditable=\"false\" href=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/newsroom\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><span lang=\"FR\">salle de r\u00e9daction<\/span><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"> <span lang=\"FR\">d<\/span>u GLF\u202fAfrica.\u00a0<\/span><\/span><\/li><li><span data-contrast=\"auto\"><span lang=\"FR\">Apprenez-en plus \u00e0 propos du #GLFAfrica sur <\/span><span lang=\"FR\"><a title=\"http:\/\/bit.ly\/GLFAfrica2022\" contenteditable=\"false\" href=\"http:\/\/bit.ly\/GLFAfrica2022\">bit.ly\/GLFAfrica2022<\/a><\/span><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/span>\u00a0<\/li><\/ul><\/div><p class=\"x_paragraph\">_________<\/p><p class=\"x_paragraph\"><span class=\"x_normaltextrun\"><b><span lang=\"FR\">\u00c0 propos du\u00a0<\/span><\/b><\/span><b><span data-contrast=\"auto\">GLF\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><i><span lang=\"FR\">Le\u00a0<\/span><\/i><\/span><\/span><a title=\"https:\/\/www.globallandscapesforum.org\/\" contenteditable=\"false\" href=\"https:\/\/www.globallandscapesforum.org\/\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><span data-ccp-charstyle=\"Hyperlink\"><i><span lang=\"FR\">Global Landscapes Forum (GLF)<\/span><\/i><\/span><\/span><\/a><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><i>\u00a0<span lang=\"FR\">est la plus grande plateforme mondiale ax\u00e9e sur les connaissances en mati\u00e8re d<\/span>\u2019utilisation int\u00e9gr\u00e9e des terres, d\u00e9di\u00e9e \u00e0 la r\u00e9alisation des Objectifs de d\u00e9veloppement durable\u00a0(ODD)\u00a0et de l\u2019Accord\u202fde\u202fParis sur le climat. Le Forum adopte une approche holistique pour cr\u00e9er des paysages durables qui\u00a0soient\u00a0productifs, prosp\u00e8res, \u00e9quitables et r\u00e9silients, et\u00a0prend en consid\u00e9ration\u00a0cinq\u202fth\u00e8mes\u00a0coh\u00e9rents\u00a0: l\u2019alimentation et les moyens de subsistance, la restauration des paysages, les droits, le financement et la mesure des progr\u00e8s.\u00a0Le Forum\u00a0est dirig\u00e9 par le\u00a0Centre de recherche foresti\u00e8re internationale\u00a0et\u00a0le\u00a0Centre international pour la recherche en agroforesterie\u00a0(CIFOR-ICRAF), en collaboration avec ses\u00a0cofondateurs, le\u00a0Programme des Nations\u202fUnies pour l\u2019environnement (PNUE)\u00a0et la Banque\u202fmondiale, et\u00a0les\u00a0<\/i><\/span><a title=\"https:\/\/www.globallandscapesforum.org\/about\/partners\/#charter\" contenteditable=\"false\" href=\"https:\/\/www.globallandscapesforum.org\/about\/partners\/#charter\" target=\"_blank\" rel=\"noopener\"><span class=\"x_normaltextrun\"><i><span lang=\"FR\">membres\u00a0signataires de la Charte<\/span><\/i><\/span><\/a><\/span><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><i><span lang=\"FR\">. Cette conf\u00e9rence num\u00e9rique a \u00e9t\u00e9 rendue possible gr\u00e2ce au soutien g\u00e9n\u00e9reux du\u00a0<\/span>minist\u00e8re f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du D\u00e9veloppement\u00a0(BMZ), du minist\u00e8re\u00a0f\u00e9d\u00e9ral allemand de l&#8217;Environnement, de la Protection de la nature, de la S\u00e9curit\u00e9 nucl\u00e9aire et de la Protection des consommateurs\u00a0(BMUV), du gouvernement du Grand-Duch\u00e9 de Luxembourg, du\u00a0Programme d\u2019impact sur les syst\u00e8mes alimentaires, l\u2019utilisation des terres et la restauration (<\/i><\/span><\/span><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">Food\u00a0<\/span>Systems, Land Use and\u00a0Restoration<i><\/i><\/span><i>\u00a0ou FOLUR), du\u00a0Fonds pour l\u2019environnement mondial (FEM)\u00a0et de la Fondation Robert Bosch\u202fStiftung.<\/i><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><\/p><p class=\"x_paragraph\"><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><span lang=\"FR\">_______________<\/span><\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\"><span class=\"x_normaltextrun\"><b><span lang=\"FR\">CITATIONS <\/span>EXTRAITES DE LA CONF\u00c9RENCE<\/b><\/span><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\"><span class=\"x_eop\"><span lang=\"FR\">\u00a0<\/span><\/span><\/span><span lang=\"FR\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdc76a5 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"cdc76a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tJamais auparavant nous n\u2019avons \u00e9t\u00e9 confront\u00e9s simultan\u00e9ment \u00e0 autant de crises mondiales qu\u2019aujourd\u2019hui. Aujourd\u2019hui, nous devons non seulement prendre des mesures contre l\u2019une des pires crises alimentaires mondiales jamais connues, mais nous devons \u00e9galement rendre nos syst\u00e8mes alimentaires davantage r\u00e9silients aux crises futures. Consid\u00e9rons cela comme une opportunit\u00e9\u202f\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/events.globallandscapesforum.org\/africa-2022\/speaker\/jochen-flasbarth\/\">Jochen Flasbarth<\/a>, Secr\u00e9taire d\u2019\u00c9tat au minist\u00e8re f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du D\u00e9veloppement (BMZ)<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d23cc5 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"3d23cc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tLa jeunesse africaine s\u2019est r\u00e9veill\u00e9e, et nous sommes d\u00e9termin\u00e9s \u00e0 faire tout ce qui est en notre pouvoir pour construire une Afrique prosp\u00e8re. Pour cela, nous avons besoin que les dirigeants africains encouragent activement les investissements dans le secteur agricole. Apr\u00e8s tout, l\u2019agriculture est le m\u00e9tier le plus formidable au monde. L\u2019agro-industrie africaine vaudra 1\u202f000 milliards de dollars d\u2019ici \u00e0 2030, et tout le monde a besoin de manger\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/64ebf7a6-c003-ed11-b47a-a04a5e7cf9da\">Ineza Grace<\/a>, coordinatrice de Loss\u202fand\u202fDamage\u202fYouth\u202fCoalition (LDYC)<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d09775f elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"d09775f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tCe n\u2019est pas parce que des acteurs ext\u00e9rieurs le demandent. C\u2019est parce que nous y croyons. Si nous sommes r\u00e9actifs, nous pouvons continuer \u00e0 vivre la m\u00eame chose. Mais si nous devenons proactifs, nous pourrions bien devenir les leaders de nouveaux syst\u00e8mes alimentaires.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/fb91f6c7-e50e-ed11-bd6e-a04a5e7d2ab9\">Carlos Lopes<\/a>, professeur honoraire, \u00e9cole de gouvernance publique Nelson\u202fMandela, universit\u00e9 de Cape\u202fTown<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce7f7ff elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"ce7f7ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tNous devons g\u00e9rer l\u2019utilisation des esp\u00e8ces sauvages pour l\u2019alimentation en examinant toute la gamme des options possibles, de la conservation pure \u00e0 l\u2019utilisation durable en passant par la domestication. Nous ne pouvons pas simplement dire aux personnes d\u00e9pendant de la viande de brousse comme principale source de prot\u00e9ines d\u2019arr\u00eater de manger de la viande sans leur proposer des alternatives abordables et saines.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/87343a05-e80e-ed11-bd6e-a04a5e7d2ab9\">Robert Nasi<\/a>, directeur g\u00e9n\u00e9ral, Centre de recherche foresti\u00e8re internationale (CIFOR)<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bae3680 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"bae3680\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tIl y a un r\u00e9cit que nous pouvons commencer \u00e0 changer. L\u2019Afrique n\u2019est pas un pays : c\u2019est un continent. L\u2019Afrique n\u2019est pas \u2018d\u00e9finie par la pauvret\u00e9\u2019 : l\u2019Afrique est riche. L\u2019Afrique est pleine d\u2019histoires\u202f; l\u2019Afrique est pleine de diversit\u00e9\u202f; elle est pleine de jeunes c\u0153urs, elle est pleine de culture, elle est pleine d\u2019innovation\u202f; elle est pleine de nouvelles id\u00e9es. Si nous voulons voir des solutions bas\u00e9es sur la nature, si nous voulons voir des contributions innovantes \u00e0 la fois dans l\u2019espace scientifique et dans l\u2019espace de conservation, alors l\u2019Afrique est le meilleur endroit o\u00f9 regarder. Et nous devons constamment nous rappeler et demander au reste du monde de ne pas d\u00e9finir l\u2019Afrique sous l\u2019angle de la pauvret\u00e9, car ce n\u2019est pas ce que nous sommes. L\u2019Afrique est riche en biodiversit\u00e9, des oc\u00e9ans \u00e0 la terre en passant par nos populations.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/43d4998e-b42c-ed11-ae83-a04a5e7d5b61\">Jamila Jana<\/a>, biologiste marine, universit\u00e9 de Stellenbosch<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ce367 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"45ce367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Prot\u00e9ger le climat du continent est essentiel pour lutter contre la pauvret\u00e9 et les crises alimentaires.\u202f\" \n\"Les petits agriculteurs produisent la nourriture, mais ils dorment l\u2019estomac vide.\u202f\" \n\"Nous avons besoin d\u2019une approche holistique \u00e0 l\u2019avenir pour g\u00e9rer les crises futures qui menacent l\u2019humanit\u00e9.\"\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/b0188287-fe28-ed11-ae83-a04a5e7d5b61\">Alvaro Lario<\/a>, s\u00e9ance pl\u00e9ni\u00e8re \u00ab\u202fSolutions africaines pour une r\u00e9silience alimentaire et climatique\u202f\u00bb\u202f; futur pr\u00e9sident du Fonds international de d\u00e9veloppement agricole (FIDA)<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a134628 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"a134628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Lorsque nous pensons \u00e0 l\u2019adaptation, notre premi\u00e8re pens\u00e9e peut concerner la r\u00e9duction des risques alimentaires ou la pr\u00e9vention des p\u00e9nuries d\u2019eau, mais ce que nous apprenons, c\u2019est que le renforcement des syst\u00e8mes de sant\u00e9 peut r\u00e9duire l\u2019impact des maladies infectieuses, du stress thermique et d\u2019autres risques li\u00e9s au climat, ainsi que les traumatismes associ\u00e9s aux chaleurs extr\u00eames.\u202f\"<br>\n\"Il existe des limites \u00e0 l\u2019adaptation. L\u2019adaptation ne peut pas emp\u00eacher toutes les pertes et tous les dommages, et m\u00eame avec une adaptation efficace, les limites seront atteintes avec des niveaux plus \u00e9lev\u00e9s de r\u00e9chauffement.\"\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\"><a href=\"https:\/\/conference.globallandscapesforum.org\/africa-2022\/speaker\/65ebf7a6-c003-ed11-b47a-a04a5e7cf9da\">Youba Sokona<\/a>, vice-pr\u00e9sident du Groupe intergouvernemental d\u2019experts sur l\u2019\u00e9volution du climat (GIEC)<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c42ffd elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"8c42ffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tDans ma culture, les arbres sont sacr\u00e9s. C\u2019est quelque chose sur lequel nous pouvons nous appuyer pour conserver la biodiversit\u00e9. Nos cultures poss\u00e8dent les solutions.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Ayo Fortunate, tribu\u202fTurr, r\u00e9gion de Karamoja<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contribue qu\u2019\u00e0 hauteur de 4\u00a0% aux \u00e9missions mondiales de gaz \u00e0 effet de serre.<\/p>\n","protected":false},"author":5,"featured_media":51220,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"location":[],"organization":[],"news_category":[],"coauthors":[720],"class_list":["post-51275","corporate_news","type-corporate_news","status-publish","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News: En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux - Global Landscapes Forum<\/title>\n<meta name=\"description\" content=\"\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contri\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News: En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux - Global Landscapes Forum\" \/>\n<meta property=\"og:description\" content=\"\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contribue qu\u2019\u00e0 hauteur de 4\u00a0% aux \u00e9missions mondiales de gaz \u00e0 effet de serre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Landscapes Forum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlobalLandscapesForum\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T06:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.globallandscapesforum.org\/wp-content\/uploads\/2022\/09\/GLF_Africa_Photo_by_Axel_Fassio_CIFOR_11.jpeg-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@globallf\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Global Landscapes Forum AM\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News: En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux - Global Landscapes Forum","description":"\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/","og_locale":"fr_FR","og_type":"article","og_title":"News: En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux - Global Landscapes Forum","og_description":"\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contribue qu\u2019\u00e0 hauteur de 4\u00a0% aux \u00e9missions mondiales de gaz \u00e0 effet de serre.","og_url":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/","og_site_name":"Global Landscapes Forum","article_publisher":"https:\/\/www.facebook.com\/GlobalLandscapesForum\/","article_modified_time":"2022-09-22T06:44:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.globallandscapesforum.org\/wp-content\/uploads\/2022\/09\/GLF_Africa_Photo_by_Axel_Fassio_CIFOR_11.jpeg-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@globallf","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes","Written by":"Global Landscapes Forum AM"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/","url":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/","name":"News: En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux - Global Landscapes Forum","isPartOf":{"@id":"https:\/\/www.globallandscapesforum.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/#primaryimage"},"image":{"@id":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.globallandscapesforum.org\/wp-content\/uploads\/2022\/09\/GLF_Africa_Photo_by_Axel_Fassio_CIFOR_11.jpeg-1.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-09-20T02:18:36+00:00","dateModified":"2022-09-22T06:44:17+00:00","description":"\u202fL\u2019humanit\u00e9 est confront\u00e9e \u00e0 une urgence climatique qui frappe l\u2019Afrique plus durement que partout ailleurs, alors que le continent ne contribue qu\u2019\u00e0 hauteur de 4\u00a0% aux \u00e9missions mondiales de gaz \u00e0 effet de serre.","breadcrumb":{"@id":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/#primaryimage","url":"https:\/\/i0.wp.com\/www.globallandscapesforum.org\/wp-content\/uploads\/2022\/09\/GLF_Africa_Photo_by_Axel_Fassio_CIFOR_11.jpeg-1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.globallandscapesforum.org\/wp-content\/uploads\/2022\/09\/GLF_Africa_Photo_by_Axel_Fassio_CIFOR_11.jpeg-1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.globallandscapesforum.org\/glf-news\/amid-global-climate-and-hunger-crises-africa-is-building-a-brighter-food-future\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.globallandscapesforum.org\/"},{"@type":"ListItem","position":2,"name":"GLF News","item":"https:\/\/www.globallandscapesforum.org\/glf-news\/"},{"@type":"ListItem","position":3,"name":"En plein pendant les crises climatiques et alimentaires mondiales, l\u2019Afrique se construit un avenir alimentaire plus radieux"}]},{"@type":"WebSite","@id":"https:\/\/www.globallandscapesforum.org\/#website","url":"https:\/\/www.globallandscapesforum.org\/","name":"Global Landscapes Forum","description":"Connect, learn and share","publisher":{"@id":"https:\/\/www.globallandscapesforum.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.globallandscapesforum.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.globallandscapesforum.org\/#organization","name":"Global Landscapes Forum","url":"https:\/\/www.globallandscapesforum.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.globallandscapesforum.org\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.globallandscapesforum.org\/wp-content\/uploads\/2018\/02\/logo_glf.png?fit=63%2C60&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.globallandscapesforum.org\/wp-content\/uploads\/2018\/02\/logo_glf.png?fit=63%2C60&ssl=1","width":63,"height":60,"caption":"Global Landscapes Forum"},"image":{"@id":"https:\/\/www.globallandscapesforum.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlobalLandscapesForum\/","https:\/\/x.com\/globallf","https:\/\/www.instagram.com\/globallandscapesforum\/","https:\/\/www.linkedin.com\/company\/globallandscapesforum","https:\/\/www.youtube.com\/globallandscapesforum"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/corporate_news\/51275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/corporate_news"}],"about":[{"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/types\/corporate_news"}],"author":[{"embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/corporate_news\/51275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/media\/51220"}],"wp:attachment":[{"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/media?parent=51275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/categories?post=51275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/tags?post=51275"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/location?post=51275"},{"taxonomy":"organization","embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/organization?post=51275"},{"taxonomy":"news_category","embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/news_category?post=51275"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.globallandscapesforum.org\/fr\/wp-json\/wp\/v2\/coauthors?post=51275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}